{"id":5164,"date":"2025-07-28T15:29:50","date_gmt":"2025-07-28T13:29:50","guid":{"rendered":"https:\/\/wp.stromer-tech.info\/ht-faq\/new-faq-question-187\/"},"modified":"2026-05-20T17:33:04","modified_gmt":"2026-05-20T15:33:04","slug":"nieuwe-faq-vraag-187","status":"publish","type":"ht_faq","link":"https:\/\/wp.stromer-tech.info\/nl\/ht-faq\/new-faq-question-187\/","title":{"rendered":"Gewicht - Hoeveel weegt een Stromer?"},"content":{"rendered":"<p class=\"wp-block-paragraph\" id=\"0dcde903-c9ce-4ff7-a88b-5ba570711028\">In de loop van de mode-evolutie werd de Stromer steeds zwaarder. Hier is een kleine samenvatting. Het is gebaseerd op gegevens van online beschikbare informatie, maar kan in de praktijk met +\/- 1 kg vari\u00ebren, afhankelijk van het frame.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"c2639369-edb8-4f98-bb55-be774f9889ac\">Het maximale systeemgewicht van de modellen is 140 kg voor de 26\u2033 modellen en 150 kg voor de 27,5\u2033 modellen. De toegestane belasting van de bagagedrager ligt tussen 18,5 en 22,5 kg.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"689\" src=\"https:\/\/wp.stromer-tech.info\/wp-content\/uploads\/2025\/07\/Stromer-Gewichtsentwicklung-Modellgeschichte-1024x689.webp\" alt=\"\" class=\"wp-image-2089\" srcset=\"https:\/\/wp.stromer-tech.info\/wp-content\/uploads\/2025\/07\/Stromer-Gewichtsentwicklung-Modellgeschichte-1024x689.webp 1024w, https:\/\/wp.stromer-tech.info\/wp-content\/uploads\/2025\/07\/Stromer-Gewichtsentwicklung-Modellgeschichte-300x202.webp 300w, https:\/\/wp.stromer-tech.info\/wp-content\/uploads\/2025\/07\/Stromer-Gewichtsentwicklung-Modellgeschichte-768x517.webp 768w, https:\/\/wp.stromer-tech.info\/wp-content\/uploads\/2025\/07\/Stromer-Gewichtsentwicklung-Modellgeschichte-50x34.webp 50w, https:\/\/wp.stromer-tech.info\/wp-content\/uploads\/2025\/07\/Stromer-Gewichtsentwicklung-Modellgeschichte-60x40.webp 60w, https:\/\/wp.stromer-tech.info\/wp-content\/uploads\/2025\/07\/Stromer-Gewichtsentwicklung-Modellgeschichte-100x67.webp 100w, https:\/\/wp.stromer-tech.info\/wp-content\/uploads\/2025\/07\/Stromer-Gewichtsentwicklung-Modellgeschichte.webp 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Im laufe der Modelevolution wurden die Stromer immer schwerer. Hier eine kleine Zusammenstellung. Sie basiert auf Daten aus online verf\u00fcgbaren Informationen kann aber in der Praxis auch je nach Rahmen +\/- 1 kg abweichen. Das max. Systemgewicht der Modelle liegt bei den 26\u2033 Modellen bei 140, den 27.5\u2033 Modellen bei&#8230;<\/p>","protected":false},"author":1,"template":"","ht-faq-group":[387],"class_list":["post-5164","ht_faq","type-ht_faq","status-publish","hentry"],"display_content":"<!-- wp:paragraph -->\n<p id=\"0dcde903-c9ce-4ff7-a88b-5ba570711028\">Im laufe der Modelevolution wurden die Stromer immer schwerer. Hier eine kleine Zusammenstellung. Sie basiert auf Daten aus online verf\u00fcgbaren Informationen kann aber in der Praxis auch je nach Rahmen +\/- 1 kg abweichen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p id=\"c2639369-edb8-4f98-bb55-be774f9889ac\">Das max. Systemgewicht der Modelle liegt bei den 26\u2033 Modellen bei 140, den 27.5\u2033 Modellen bei 150 kg. Die zul\u00e4ssige Gep\u00e4cktr\u00e4gerlast bewegt sich zwischen 18.5 und 22.5 kg.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":2089} -->\n<figure class=\"wp-block-image\"><img src=\"https:\/\/wp.stromer-tech.info\/wp-content\/uploads\/2025\/07\/Stromer-Gewichtsentwicklung-Modellgeschichte-1024x689.webp\" alt=\"\" class=\"wp-image-2089\"\/><\/figure>\n<!-- \/wp:image -->","display_excerpt":"Im laufe der Modelevolution wurden die Stromer immer schwerer. Hier eine kleine Zusammenstellung. Sie basiert auf Daten aus online verf\u00fcgbaren Informationen kann aber in der Praxis auch je nach Rahmen +\/- 1 kg abweichen. Das max. Systemgewicht der Modelle liegt bei den 26\u2033 Modellen bei 140, den 27.5\u2033 Modellen bei...","_ht_faq_order":"52","_ht_faq_enabled":"1","_links":{"self":[{"href":"https:\/\/wp.stromer-tech.info\/nl\/wp-json\/wp\/v2\/ht-faq\/5164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.stromer-tech.info\/nl\/wp-json\/wp\/v2\/ht-faq"}],"about":[{"href":"https:\/\/wp.stromer-tech.info\/nl\/wp-json\/wp\/v2\/types\/ht_faq"}],"author":[{"embeddable":true,"href":"https:\/\/wp.stromer-tech.info\/nl\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":3,"href":"https:\/\/wp.stromer-tech.info\/nl\/wp-json\/wp\/v2\/ht-faq\/5164\/revisions"}],"predecessor-version":[{"id":5458,"href":"https:\/\/wp.stromer-tech.info\/nl\/wp-json\/wp\/v2\/ht-faq\/5164\/revisions\/5458"}],"wp:attachment":[{"href":"https:\/\/wp.stromer-tech.info\/nl\/wp-json\/wp\/v2\/media?parent=5164"}],"wp:term":[{"taxonomy":"ht_faq_group","embeddable":true,"href":"https:\/\/wp.stromer-tech.info\/nl\/wp-json\/wp\/v2\/ht-faq-group?post=5164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}